{"id":38594,"date":"2021-05-03T12:47:28","date_gmt":"2021-05-03T12:47:28","guid":{"rendered":"https:\/\/sure-antennas68068.e.wpstage.net\/contact-us\/"},"modified":"2025-04-16T11:42:14","modified_gmt":"2025-04-16T11:42:14","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/sure-antennas.com\/de\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p> [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/sure-antennas.com\/de\/kontakt\/\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/contact.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-38594","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kontaktieren Sie uns hier bei Sure Antennas und wir werden uns bei Ihnen melden.<\/title>\n<meta name=\"description\" content=\"Sure Antennas, seit \u00fcber 30 Jahren Experten f\u00fcr Antennentechnologie. Spezialisiert auf die Herstellung von verdeckten und offenen Antennen. Kontaktieren Sie uns noch heute f\u00fcr ein Angebot.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sure-antennas.com\/de\/kontakt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kontaktieren Sie uns hier bei Sure Antennas und wir werden uns bei Ihnen melden.\" \/>\n<meta property=\"og:description\" content=\"Sure Antennas, seit \u00fcber 30 Jahren Experten f\u00fcr Antennentechnologie. Spezialisiert auf die Herstellung von verdeckten und offenen Antennen. Kontaktieren Sie uns noch heute f\u00fcr ein Angebot.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sure-antennas.com\/de\/kontakt\/\" \/>\n<meta property=\"og:site_name\" content=\"Sure Antennas\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T11:42:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/de\\\/kontakt\\\/\",\"url\":\"https:\\\/\\\/sure-antennas.com\\\/de\\\/kontakt\\\/\",\"name\":\"Kontaktieren Sie uns hier bei Sure Antennas und wir werden uns bei Ihnen melden.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/#website\"},\"datePublished\":\"2021-05-03T12:47:28+00:00\",\"dateModified\":\"2025-04-16T11:42:14+00:00\",\"description\":\"Sure Antennas, seit \u00fcber 30 Jahren Experten f\u00fcr Antennentechnologie. Spezialisiert auf die Herstellung von verdeckten und offenen Antennen. Kontaktieren Sie uns noch heute f\u00fcr ein Angebot.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/de\\\/kontakt\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sure-antennas.com\\\/de\\\/kontakt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/de\\\/kontakt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sure-antennas.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/#website\",\"url\":\"https:\\\/\\\/sure-antennas.com\\\/\",\"name\":\"Sure Antennas\",\"description\":\"Sure Antennas site\",\"publisher\":{\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sure-antennas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/#organization\",\"name\":\"Sure Antennas\",\"url\":\"https:\\\/\\\/sure-antennas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sure-antennas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/sure-antennas.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-1.png\",\"width\":211,\"height\":52,\"caption\":\"Sure Antennas\"},\"image\":{\"@id\":\"https:\\\/\\\/sure-antennas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kontaktieren Sie uns hier bei Sure Antennas und wir werden uns bei Ihnen melden.","description":"Sure Antennas, seit \u00fcber 30 Jahren Experten f\u00fcr Antennentechnologie. Spezialisiert auf die Herstellung von verdeckten und offenen Antennen. Kontaktieren Sie uns noch heute f\u00fcr ein Angebot.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sure-antennas.com\/de\/kontakt\/","og_locale":"de_DE","og_type":"article","og_title":"Kontaktieren Sie uns hier bei Sure Antennas und wir werden uns bei Ihnen melden.","og_description":"Sure Antennas, seit \u00fcber 30 Jahren Experten f\u00fcr Antennentechnologie. Spezialisiert auf die Herstellung von verdeckten und offenen Antennen. Kontaktieren Sie uns noch heute f\u00fcr ein Angebot.","og_url":"https:\/\/sure-antennas.com\/de\/kontakt\/","og_site_name":"Sure Antennas","article_modified_time":"2025-04-16T11:42:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sure-antennas.com\/de\/kontakt\/","url":"https:\/\/sure-antennas.com\/de\/kontakt\/","name":"Kontaktieren Sie uns hier bei Sure Antennas und wir werden uns bei Ihnen melden.","isPartOf":{"@id":"https:\/\/sure-antennas.com\/#website"},"datePublished":"2021-05-03T12:47:28+00:00","dateModified":"2025-04-16T11:42:14+00:00","description":"Sure Antennas, seit \u00fcber 30 Jahren Experten f\u00fcr Antennentechnologie. Spezialisiert auf die Herstellung von verdeckten und offenen Antennen. Kontaktieren Sie uns noch heute f\u00fcr ein Angebot.","breadcrumb":{"@id":"https:\/\/sure-antennas.com\/de\/kontakt\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sure-antennas.com\/de\/kontakt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sure-antennas.com\/de\/kontakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sure-antennas.com\/de\/"},{"@type":"ListItem","position":2,"name":"Kontakt"}]},{"@type":"WebSite","@id":"https:\/\/sure-antennas.com\/#website","url":"https:\/\/sure-antennas.com\/","name":"Sure Antennas","description":"Sure Antennas site","publisher":{"@id":"https:\/\/sure-antennas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sure-antennas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/sure-antennas.com\/#organization","name":"Sure Antennas","url":"https:\/\/sure-antennas.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/sure-antennas.com\/#\/schema\/logo\/image\/","url":"https:\/\/sure-antennas.com\/wp-content\/uploads\/2021\/04\/logo-1.png","contentUrl":"https:\/\/sure-antennas.com\/wp-content\/uploads\/2021\/04\/logo-1.png","width":211,"height":52,"caption":"Sure Antennas"},"image":{"@id":"https:\/\/sure-antennas.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/pages\/38594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/comments?post=38594"}],"version-history":[{"count":0,"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/pages\/38594\/revisions"}],"wp:attachment":[{"href":"https:\/\/sure-antennas.com\/de\/wp-json\/wp\/v2\/media?parent=38594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}